{"id":825,"date":"2012-05-10T11:38:56","date_gmt":"2012-05-10T10:38:56","guid":{"rendered":"http:\/\/www.proantic.com\/magazine\/?p=825"},"modified":"2017-12-22T11:33:19","modified_gmt":"2017-12-22T10:33:19","slug":"faience-fine-pont-aux-choux","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/","title":{"rendered":"La fa\u00efence fine de Pont-aux-Choux"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>La Manufacture de <em>Pont-aux-Choux <\/em>est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0, transf\u00e9r\u00e9e en 1749 sur la contrescarpe en face de la rue du Pont-aux-Choux, ferm\u00e9e en 1788, apr\u00e8s 53 ans d&rsquo;existence.<\/strong><\/p>\n<p><span style=\"font-size: 14pt;color: #ff0000\">E<\/span>lle est connue et r\u00e9pertori\u00e9e en 1772 dans l&rsquo;<em>Almanach g\u00e9n\u00e9ral des Marchands<\/em>, sous le nom de &lsquo;Manufacture Royale des Terres de France, \u00e0 l&rsquo;imitation de celle d&rsquo;Angleterre&rsquo; et est c\u00e9l\u00e8bre pour ses fa\u00efences fines \u00e0 reliefs de couleur ivoire. On lui attribue de grandes pi\u00e8ces de services, si \u00e9troitement apparent\u00e9es \u00e0 l&rsquo;argenterie des orf\u00e8vres parisiens contemporains qu&rsquo;on a pu croire que les potiers avaient surmoul\u00e9 des \u0153uvres de m\u00e9tal.<\/p>\n<figure id=\"attachment_826\" aria-describedby=\"caption-attachment-826\" style=\"width: 363px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"826\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/73413812_p\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?fit=363%2C450&amp;ssl=1\" data-orig-size=\"363,450\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Chocolati\u00e8re en Fa\u00efence fine, Manufacture du Pont-aux-choux\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Chocolati\u00e8re en Fa\u00efence fine, Manufacture du Pont-aux-choux&lt;\/p&gt;\n&lt;p&gt;(C) RMN &amp;#8211; Martine Beck-Coppola&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?fit=242%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?fit=363%2C450&amp;ssl=1\" class=\"size-full wp-image-826\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?resize=363%2C450\" alt=\" Manufacture du Pont-aux-choux\" width=\"363\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?w=363&amp;ssl=1 363w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413812_p.jpg?resize=242%2C300&amp;ssl=1 242w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><\/a><figcaption id=\"caption-attachment-826\" class=\"wp-caption-text\">Chocolati\u00e8re en Fa\u00efence fine, Manufacture du Pont-aux-choux<br \/>(C) RMN &#8211; Martine Beck-Coppola<\/figcaption><\/figure>\n<p><span style=\"font-size: 14pt;color: #ff0000\">A<\/span>vec la fin du XVIIIe si\u00e8cle l&rsquo;industrie de la fa\u00efence fine prit un essor dans toute la r\u00e9gion parisienne, car les potiers trouvaient des gisements d&rsquo;argile tr\u00e8s pure aux portes de la capitale. Une terre blanche poreuse et opaque, contrairement \u00e0 la porcelaine est rendue imperm\u00e9able gr\u00e2ce \u00e0 un vernis cristallin plombif\u00e8re qui ne masque pas la p\u00e2te d\u00e9j\u00e0 blanche de la fa\u00efence fine.. Cette terre tr\u00e8s mall\u00e9able permettait de ciseler des d\u00e9cors en reliefs d&rsquo;une grande pr\u00e9cision. Cette technique de fabrication est une d\u00e9couverte anglaise destin\u00e9e \u00e0 rivaliser avec la porcelaine en se rapprochant le plus possible de son aspect pour un co\u00fbt inf\u00e9rieur.<\/p>\n<figure id=\"attachment_827\" aria-describedby=\"caption-attachment-827\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"827\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/73413896_p\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&amp;ssl=1\" data-orig-size=\"450,338\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Pot \u00e0 Lait Couvert En Fa\u00efence Fine De Pont Aux Choux\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Pot \u00e0 Lait Couvert En Fa\u00efence Fine De Pont Aux Choux (paris) -XVIII\u00e8me Si\u00e8cle&lt;\/p&gt;\n&lt;p&gt;(c) source Proantic, Galerie Orely&amp;rsquo;s&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&amp;ssl=1\" class=\"size-full wp-image-827\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?resize=450%2C338\" alt=\"Fa\u00efence Fine De Pont Aux Choux\" width=\"450\" height=\"338\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?w=450&amp;ssl=1 450w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption id=\"caption-attachment-827\" class=\"wp-caption-text\">Pot \u00e0 Lait Couvert En Fa\u00efence Fine De Pont Aux Choux (paris) -XVIII\u00e8me Si\u00e8cle<br \/>(c) source Proantic, Galerie Orely&rsquo;s<\/figcaption><\/figure>\n<p><span style=\"font-size: 14pt;color: #ff0000\">L<\/span>a manufacture de pont aux choux ne r\u00e9sista \u00e0 la dangereuse concurrence des produits import\u00e9s d&rsquo;Angleterre qu&rsquo;en adoptant des proc\u00e9d\u00e9s m\u00e9caniques. Les progr\u00e8s techniques de production lui permirent de fabriquer toute une gamme d&rsquo;objets usuels \u00e0 bon march\u00e9.<\/p>\n<p><span style=\"font-size: 14pt;color: #ff0000\">A<\/span>u XIXe si\u00e8cle, la fa\u00efence fine conna\u00eet un tr\u00e8s fort d\u00e9veloppement\u00a0 gr\u00e2ce aux manufacture de fa\u00efence de Creil- Montereau, de Choisy-le-roi et de Vieillard \u00e0 Bordeaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0, transf\u00e9r\u00e9e en 1749 sur la contrescarpe en face de la rue du Pont-aux-Choux, ferm\u00e9e en 1788, apr\u00e8s 53 ans d&rsquo;existence. Elle est connue et r\u00e9pertori\u00e9e en 1772 dans l&rsquo;Almanach g\u00e9n\u00e9ral des [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[180],"tags":[138,159],"class_list":["post-825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arts-decoratifs-proantic","tag-faience","tag-pont-aux-choux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-10T10:38:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-22T10:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"headline\":\"La fa\u00efence fine de Pont-aux-Choux\",\"datePublished\":\"2012-05-10T10:38:56+00:00\",\"dateModified\":\"2017-12-22T10:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\"},\"wordCount\":386,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1\",\"keywords\":[\"fa\u00efence\",\"Pont Aux Choux\"],\"articleSection\":[\"Arts d\u00e9coratifs sur Proantic\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\",\"name\":\"La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1\",\"datePublished\":\"2012-05-10T10:38:56+00:00\",\"dateModified\":\"2017-12-22T10:33:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"description\":\"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1\",\"width\":450,\"height\":338,\"caption\":\"Pot \u00e0 Lait Couvert En Fa\u00efence Fine De Pont Aux Choux (paris) -XVIII\u00e8me Si\u00e8cle (c) source Proantic, Galerie Orely's\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fa\u00efence fine de Pont-aux-Choux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic","description":"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/","og_locale":"fr_FR","og_type":"article","og_title":"La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic","og_description":"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,","og_url":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2012-05-10T10:38:56+00:00","article_modified_time":"2017-12-22T10:33:19+00:00","og_image":[{"width":450,"height":338,"url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","type":"image\/jpeg"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"headline":"La fa\u00efence fine de Pont-aux-Choux","datePublished":"2012-05-10T10:38:56+00:00","dateModified":"2017-12-22T10:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/"},"wordCount":386,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","keywords":["fa\u00efence","Pont Aux Choux"],"articleSection":["Arts d\u00e9coratifs sur Proantic"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/","url":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/","name":"La fa\u00efence fine de Pont-aux-Choux Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","datePublished":"2012-05-10T10:38:56+00:00","dateModified":"2017-12-22T10:33:19+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"description":"La Manufacture de Pont-aux-Choux est une manufacture fran\u00e7aise du XVIII\u00e8me si\u00e8cle de fa\u00efence fine et de porcelaine , cr\u00e9\u00e9e en 1743 rue de Charenton\u00a0,","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","width":450,"height":338,"caption":"Pot \u00e0 Lait Couvert En Fa\u00efence Fine De Pont Aux Choux (paris) -XVIII\u00e8me Si\u00e8cle (c) source Proantic, Galerie Orely's"},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/faience-fine-pont-aux-choux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"La fa\u00efence fine de Pont-aux-Choux"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2014\/04\/73413896_p.jpg?fit=450%2C338&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-dj","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":0,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/827"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}