{"id":7580,"date":"2017-09-29T11:04:08","date_gmt":"2017-09-29T10:04:08","guid":{"rendered":"http:\/\/www.proantic.com\/magazine\/?p=7580"},"modified":"2017-10-01T15:03:20","modified_gmt":"2017-10-01T14:03:20","slug":"grand-tour-voyage-de-noblesses-europeennes","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/","title":{"rendered":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes"},"content":{"rendered":"<p><strong>Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l&rsquo;origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes filles, des plus hautes classes de la soci\u00e9t\u00e9 europ\u00e9enne, britannique, allemande, mais aussi fran\u00e7aise, n\u00e9erlandaise, polonaise, scandinave, plus tardivement russe \u00e0 partir des ann\u00e9es 1760.<\/strong> La pratique, qui \u00e9merge vers le milieu du XVI\u00e8me si\u00e8cle, s&rsquo;affirme tout au long du XVI\u00e8me si\u00e8cle, pour culminer au XVIII \u00e8me si\u00e8cle. Ce voyage d&rsquo;\u00e9ducation aristocratique est destin\u00e9 \u00e0 parfaire leur \u00e9ducation et \u00e9lever leurs centres d&rsquo;int\u00e9r\u00eat, juste apr\u00e8s, ou pendant leurs \u00e9tudes, qui \u00e9taient alors essentiellement fond\u00e9es sur les humanit\u00e9s grecques et latines.<\/p>\n<figure id=\"attachment_7609\" aria-describedby=\"caption-attachment-7609\" style=\"width: 665px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7609\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/276145-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Grand Tour, Vue des \u00ab\u00a0fori Imperiali\u00a0\u00bb, Gravure de Fran\u00e7ois Morel 1796. (c) Antiquit\u00e9s Ghilli, Proantic.\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Grand Tour, Vue des \u00ab\u00a0fori Imperiali\u00a0\u00bb, Gravure de Fran\u00e7ois Morel 1796.&lt;br \/&gt;\n(c) Antiquit\u00e9s Ghilli, Proantic.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?fit=665%2C499&amp;ssl=1\" class=\"size-large wp-image-7609\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1-1024x768.jpg?resize=665%2C499\" alt=\"\" width=\"665\" height=\"499\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/276145-1.jpg?resize=180%2C135&amp;ssl=1 180w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption id=\"caption-attachment-7609\" class=\"wp-caption-text\">Grand Tour, Vue des \u00ab\u00a0fori Imperiali\u00a0\u00bb, Gravure de Fran\u00e7ois Morel 1796.<br \/>(c) Antiquit\u00e9s Ghilli, Proantic.<\/figcaption><\/figure>\n<p>Les destinations principales sont avant tout l&rsquo;Italie, mais aussi la France, les Pays-Bas, l&rsquo;Allemagne et la Suisse que le jeune homme parcourt en partant et en revenant dans son pays. Plus tard, \u00e0 partir du milieu du xviiie si\u00e8cle, certains se hasardent jusqu&rsquo;en Gr\u00e8ce et au Proche-Orient, parfois en Perse. Ces voyages duraient en g\u00e9n\u00e9ral plusieurs ann\u00e9es, jusqu&rsquo;\u00e0 cinq ou six pour les familles les plus fortun\u00e9es, ou les jeunes gens les plus ambitieux ; ils \u00e9taient le plus souvent effectu\u00e9s en compagnie d\u2019un tuteur. Ils devinrent une pratique normale, voire n\u00e9cessaire \u00e0 toute bonne \u00e9ducation pour des jeunes gens destin\u00e9s \u00e0 de hautes carri\u00e8res ou simplement issus de l&rsquo;aristocratie cultiv\u00e9e.<\/p>\n<figure id=\"attachment_7627\" aria-describedby=\"caption-attachment-7627\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7627\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/249100-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?fit=1000%2C742&amp;ssl=1\" data-orig-size=\"1000,742\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bo\u00eete (\u00e0 pilule) en laiton dor\u00e9 filigran\u00e9 et micro mosa\u00efque, repr\u00e9sentant une vue de la Place Saint-Pierre \u00e0 Rome sur le dessus, d&amp;rsquo;\u00e9poque XIX\u00e8me si\u00e8cle. (c) Luc de Laval, proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;bo\u00eete (\u00e0 pilule) en laiton dor\u00e9 filigran\u00e9 et micro mosa\u00efque, repr\u00e9sentant une vue de la Place Saint-Pierre \u00e0 Rome sur le dessus, d&amp;rsquo;\u00e9poque XIX\u00e8me si\u00e8cle.&lt;br \/&gt;\n(c) Luc de Laval, proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?fit=300%2C223&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?fit=665%2C493&amp;ssl=1\" class=\"wp-image-7627\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?resize=500%2C371\" alt=\"\" width=\"500\" height=\"371\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?resize=300%2C223&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?resize=768%2C570&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-2.jpg?resize=180%2C134&amp;ssl=1 180w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-7627\" class=\"wp-caption-text\">bo\u00eete (\u00e0 pilule) en laiton dor\u00e9 filigran\u00e9 et micro mosa\u00efque, repr\u00e9sentant une vue de la Place Saint-Pierre \u00e0 Rome sur le dessus, d&rsquo;\u00e9poque XIX\u00e8me si\u00e8cle.<br \/> (c) Luc de Laval, proantic<\/figcaption><\/figure>\n<p>Aux XVIII\u00e8me e et XIX\u00e8me si\u00e8cles, le Grand Tour \u00e9tait l&rsquo;apanage des amateurs d&rsquo;art, des collectionneurs et des \u00e9crivains, dont Goethe et Alexandre Dumas. Le Grand Tour eut entre autres pour effet de mettre en contact la haute soci\u00e9t\u00e9 de l&rsquo;Europe du Nord avec l\u2019art antique et aida \u00e0 la diffusion du palladianisme et du n\u00e9oclassicisme.<\/p>\n<p>HISTOIRE DU GRAND TOUR<\/p>\n<p>L&rsquo;histoire de l&rsquo;expression \u00ab\u00a0Grand Tour\u00a0\u00bb est complexe\u00a0: si le terme d&rsquo;origine anglo-saxonne\u00a0apparait dans la seconde moiti\u00e9 du XVII\u00e8me si\u00e8cle, il est rarement utilis\u00e9 par les contemporains. Il a en revanche connu une grande fortune chez les historiens \u00e0 partir des ann\u00e9es 1960, avant de faire l&rsquo;objet d&rsquo;\u00e9tudes en nombre croissant par la suite. Il est aussi devenu une extraordinaire fa\u00e7on de promotion commerciale, en particulier dans l&rsquo;univers du tourisme. Quelques grandes expositions, \u00e0 partir des ann\u00e9es 1990, ont achev\u00e9 d&rsquo;en faire un objet \u00e9tonnant de fascination, de la part d&rsquo;un large public.<\/p>\n<figure id=\"attachment_7603\" aria-describedby=\"caption-attachment-7603\" style=\"width: 665px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7603\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/236666-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?fit=1024%2C916&amp;ssl=1\" data-orig-size=\"1024,916\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Boite \u00e0 timbres en agathe , Souvenir Du Grand Tour , XIXe Siecle. (c) Le B\u00fbcher des Vanit\u00e9s, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Boite \u00e0 timbres en agathe , Souvenir Du Grand Tour , XIXe Siecle.&lt;br \/&gt;\n(c) Le B\u00fbcher des Vanit\u00e9s, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?fit=300%2C268&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?fit=665%2C595&amp;ssl=1\" class=\"size-large wp-image-7603\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1-1024x916.jpg?resize=665%2C595\" alt=\"\" width=\"665\" height=\"595\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?resize=300%2C268&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?resize=768%2C687&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/236666-1.jpg?resize=180%2C161&amp;ssl=1 180w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption id=\"caption-attachment-7603\" class=\"wp-caption-text\">Boite \u00e0 timbres en agathe , Souvenir Du Grand Tour , XIXe Siecle.<br \/>(c) Le B\u00fbcher des Vanit\u00e9s, Proantic<\/figcaption><\/figure>\n<p>D\u00e8s le\u00a0Moyen \u00c2ge, les \u00e9tudiants de familles nobles pratiquaient la\u00a0<i>peregrinatio academica<\/i>, p\u00e9r\u00e9grination acad\u00e9mique consistant \u00e0 se \u00ab\u00a0d\u00e9placer\u00a0\u00bb d&rsquo;une universit\u00e9 \u00e0 l&rsquo;autre. Cette pratique m\u00e9di\u00e9vale perdit progressivement son sens avec la coupure de l&rsquo;Europe universitaire, \u00e0 partir du XVI \u00e8me\u00a0si\u00e8cle, en fonction des barri\u00e8res confessionnelles et \u00e9tatiques, puis avec la disparition du latin comme langue internationale d&rsquo;enseignement universitaire.<\/p>\n<figure id=\"attachment_7604\" aria-describedby=\"caption-attachment-7604\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7604\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/203445-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?fit=802%2C1200&amp;ssl=1\" data-orig-size=\"802,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cam\u00e9e, travail Italien du d\u00e9but du XIX\u00e8me \u00e9poque du Grand tour. (c) Antoine Claeys &amp;#8211; Maison du XV\u00e8me,  Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Cam\u00e9e, travail Italien du d\u00e9but du XIX\u00e8me \u00e9poque du Grand tour.&lt;br \/&gt;\n(c) Antoine Claeys &amp;#8211; Maison du XV\u00e8me,  Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?fit=201%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?fit=665%2C996&amp;ssl=1\" class=\"wp-image-7604\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4-684x1024.jpg?resize=500%2C748\" alt=\"\" width=\"500\" height=\"748\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?resize=768%2C1149&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?resize=120%2C180&amp;ssl=1 120w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/203445-4.jpg?w=802&amp;ssl=1 802w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-7604\" class=\"wp-caption-text\">Cam\u00e9e, travail Italien du d\u00e9but du XIX\u00e8me \u00e9poque du Grand tour.<br \/> (c) Antoine Claeys &#8211; Maison du XV\u00e8me, Proantic<\/figcaption><\/figure>\n<p>La pratique renaquit au milieu du XVI\u00e8me\u00a0si\u00e8cle sous le nom de Grand Tour, appel\u00e9 aussi, dans les pays du\u00a0Saint-Empire romain germanique,\u00a0<i>Junkerfahrt<\/i>\u00a0ou\u00a0<i>Cavaliertour<\/i>, qui avait d&rsquo;abord pour but de parfaire les humanit\u00e9s et la pratique des arts de la cour (art \u00e9questre, escrime, musique, danse) des jeunes gens de l&rsquo;aristocratie. Le voyage leur permettait de devenir un \u00ab\u00a0<i>compleat gentleman<\/i>\u00a0\u00bb (Peacham, 1623). Il servait \u00e0 la formation politique des jeunes gens, leur permettant de comparer les syst\u00e8mes politiques de\u00a0Grande-Bretagne\u00a0(puis du\u00a0Royaume-Uni) et des \u00c9tats continentaux. Il leur permettait aussi de nouer des liens amicaux avec des individus du m\u00eame milieu social, promis au m\u00eame type d&rsquo;avenir diplomatique, militaire, politique ou commercial dans les autres pays.<\/p>\n<figure id=\"attachment_7605\" aria-describedby=\"caption-attachment-7605\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7605\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/142617-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?fit=768%2C1024&amp;ssl=1\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gravure en couleur XIXe , Fresque Antique. Souvenir Du Grand Tour. Pompei. (c) Le B\u00fbcher des Vanit\u00e9s, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Gravure en couleur XIXe , Fresque Antique. Souvenir Du Grand Tour. Pompei.&lt;br \/&gt;\n(c) Le B\u00fbcher des Vanit\u00e9s, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?fit=665%2C887&amp;ssl=1\" class=\"wp-image-7605\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1-768x1024.jpg?resize=500%2C667\" alt=\"\" width=\"500\" height=\"667\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/142617-1.jpg?resize=135%2C180&amp;ssl=1 135w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-7605\" class=\"wp-caption-text\">Gravure en couleur XIXe , Fresque Antique. Souvenir Du Grand Tour. Pompei.<br \/> (c) Le B\u00fbcher des Vanit\u00e9s, Proantic<\/figcaption><\/figure>\n<p>La d\u00e9couverte de la superstition des populations rencontr\u00e9es \u00e9tait aussi cens\u00e9e renforcer l&rsquo;anglicanisme\u00a0des voyageurs. C&rsquo;\u00e9tait au cours du Grand Tour enfin que les jeunes gens se frottaient aux langues vivantes. Le Grand Tour avait parfois une derni\u00e8re fonction \u00e9ducatrice\u00a0: l&rsquo;\u00e9ducation sexuelle. L&rsquo;\u00e9tape \u00e0\u00a0Venise\u00a0avait longtemps servi ce but, servant \u00e0 traiter des chagrins d&rsquo;amour ou offrant un programme \u00e9rotique inavou\u00e9.<\/p>\n<p>Cependant d&rsquo;autres familles, notamment allemandes et hollandaises, chaperonnaient leur fils avec un tuteur strict pour les surveiller et leur emp\u00eacher ce genre de relations, de peur que leur fils ne soit victime de\u00a0maladies v\u00e9n\u00e9riennes. C&rsquo;\u00e9tait notamment le cas des riches familles de n\u00e9gociants qui ensuite pla\u00e7aient leur fils dans diff\u00e9rents bureaux ou comptoirs de leur r\u00e9seau et ne voulaient pas courir de risque mortel.<\/p>\n<figure id=\"attachment_7606\" aria-describedby=\"caption-attachment-7606\" style=\"width: 665px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7606\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/285556-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?fit=1200%2C900&amp;ssl=1\" data-orig-size=\"1200,900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Collection de moulages en pl\u00e2tre du grand tour. (c) Galleria dei Coronari, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Collection de moulages en pl\u00e2tre du grand tour.&lt;br \/&gt;\n(c) Galleria dei Coronari, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?fit=665%2C499&amp;ssl=1\" class=\"size-large wp-image-7606\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1-1024x768.jpg?resize=665%2C499\" alt=\"\" width=\"665\" height=\"499\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?resize=180%2C135&amp;ssl=1 180w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/285556-1.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption id=\"caption-attachment-7606\" class=\"wp-caption-text\">Collection de moulages en pl\u00e2tre du grand tour.<br \/>(c) Galleria dei Coronari, Proantic<\/figcaption><\/figure>\n<p>Au retour, le voyage avait une fonction sociale. Il constituait un \u00e9l\u00e9ment de reconnaissance ou d&rsquo;ascension sociale. Il affirmait les moyens financiers, et la culture du voyageur, avant son d\u00e9part, et \u00e0 son retour. Le but du voyage n&rsquo;\u00e9tait pas d&rsquo;aller voir autre chose, d&rsquo;aller se forger une culture propre, mais d&rsquo;aller voir ce qui devait \u00eatre vu, de se forger une culture commune. L&rsquo;important \u00e9tait de pouvoir au retour partager des anecdotes et des souvenirs. C&rsquo;\u00e9tait pour cette raison que l&rsquo;on visitait toujours les m\u00eames hauts lieux culturels. Le r\u00e9cit de voyage avait alors une fonction importante, celle de faire reconna\u00eetre cette exp\u00e9rience acquise et cette culture commune qui renforceraient les liens sociaux.<\/p>\n<figure id=\"attachment_7607\" aria-describedby=\"caption-attachment-7607\" style=\"width: 665px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7607\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/277109-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"277109-1\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Bougeoir inspir\u00e9 des formes de lampe \u00e0 huile sous l&amp;rsquo;antiquit\u00e9.. Objet du Grand Tour XIX\u00e8me.&lt;br \/&gt;\n(c) &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?fit=665%2C374&amp;ssl=1\" class=\"size-large wp-image-7607\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1-1024x576.jpg?resize=665%2C374\" alt=\"\" width=\"665\" height=\"374\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?resize=180%2C101&amp;ssl=1 180w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/277109-1.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption id=\"caption-attachment-7607\" class=\"wp-caption-text\">Bougeoir inspir\u00e9 des formes de lampe \u00e0 huile sous l&rsquo;antiquit\u00e9.. Objet du Grand Tour XIX\u00e8me.<br \/>(c) Haga Baltique, Proantic.<\/figcaption><\/figure>\n<p>Au cours de ces voyages, les jeunes gens achetaient, suivant leurs moyens, des pi\u00e8ces d\u2019art et d\u2019antiquit\u00e9s et visitaient les ruines antiques\u00a0romaines, ainsi que\u00a0Pomp\u00e9i\u00a0et\u00a0Herculanum\u00a0qui avaient \u00e9t\u00e9 r\u00e9cemment d\u00e9couverts. Au retour, les jeunes gens pouvaient alors adh\u00e9rer \u00e0 la\u00a0Soci\u00e9t\u00e9 des Dilettanti, puisque la principale condition pour y entrer \u00e9tait d&rsquo;avoir voyag\u00e9 en\u00a0Italie\u00a0et d&rsquo;avoir un int\u00e9r\u00eat pour l&rsquo;art et les antiquit\u00e9s.<\/p>\n<figure id=\"attachment_7611\" aria-describedby=\"caption-attachment-7611\" style=\"width: 665px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7611\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/254576-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?fit=1024%2C1016&amp;ssl=1\" data-orig-size=\"1024,1016\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Coupe en bronze , d\u00e9cor \u00e0 l&amp;rsquo;Antique , souvenir du Grand Tour. (c)  Le B\u00fbcher des Vanit\u00e9s, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Coupe en bronze , d\u00e9cor \u00e0 l&amp;rsquo;Antique , souvenir du Grand Tour.&lt;br \/&gt;\n(c)  Le B\u00fbcher des Vanit\u00e9s, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?fit=300%2C298&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?fit=665%2C660&amp;ssl=1\" class=\"size-large wp-image-7611\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1-1024x1016.jpg?resize=665%2C660\" alt=\"\" width=\"665\" height=\"660\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?resize=300%2C298&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?resize=768%2C762&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/254576-1.jpg?resize=180%2C180&amp;ssl=1 180w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption id=\"caption-attachment-7611\" class=\"wp-caption-text\">Coupe en bronze , d\u00e9cor \u00e0 l&rsquo;Antique , souvenir du Grand Tour.<br \/>(c) Le B\u00fbcher des Vanit\u00e9s, Proantic<\/figcaption><\/figure>\n<p>Une \u00e9tape importante du voyage \u00e9tait la r\u00e9alisation pendant leur s\u00e9jour prolong\u00e9 \u00e0 Rome d&rsquo;un portrait par l&rsquo;un des peintres en vue du moment. Parmi les peintres italiens qui b\u00e9n\u00e9ficiaient de cette client\u00e8le, citons\u00a0Pompeo Batoni,\u00a0Canaletto, et\u00a0Piran\u00e8se. De nombreux peintres, graveurs et sculpteurs \u00e9trangers vivant \u00e0 Rome, notamment les \u00e9l\u00e8ves de l\u2019Acad\u00e9mie de France \u00e0 Rome, b\u00e9n\u00e9ficiaient aussi de cette pratique. Ils vendaient leurs \u0153uvres et parfois louaient leur service en tant que guide. Il en est ainsi pour les Allemands\u00a0Mengs\u00a0et\u00a0Maron\u00a0par exemple.<\/p>\n<figure id=\"attachment_7626\" aria-describedby=\"caption-attachment-7626\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7626\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/hnhy\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?fit=947%2C726&amp;ssl=1\" data-orig-size=\"947,726\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1506322375&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ensemble de 16 gouaches repr\u00e9sentants des vues de Naples, Grand Tour, 19\u00e8me si\u00e8cle. (c) Borrelli Antichit\u00e0, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ensemble de 16 gouaches repr\u00e9sentants des vues de Naples, Grand Tour, 19\u00e8me si\u00e8cle. (c) Borrelli Antichit\u00e0, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?fit=300%2C230&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?fit=665%2C510&amp;ssl=1\" class=\"wp-image-7626\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?resize=500%2C383\" alt=\"\" width=\"500\" height=\"383\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?w=947&amp;ssl=1 947w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?resize=300%2C230&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?resize=768%2C589&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/hnhy.jpg?resize=180%2C138&amp;ssl=1 180w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-7626\" class=\"wp-caption-text\">Ensemble de 16 gouaches repr\u00e9sentants des vues de Naples, Grand Tour, 19\u00e8me si\u00e8cle. (c) Borrelli Antichit\u00e0, Proantic<\/figcaption><\/figure>\n<p>Les voyageurs les plus fortun\u00e9s se faisaient peindre \u00e0 c\u00f4t\u00e9 d&rsquo;un monument c\u00e9l\u00e8bre, d&rsquo;autres achetaient des vues peintes ou grav\u00e9es des monuments visit\u00e9s (voir\u00a0Abraham-Louis-Rodolphe Ducros\u00a0\u00e0 Rome et \u00e0 Naples). Ces souvenirs, dispos\u00e9s dans leurs demeures, rappelaient aux visiteurs qu&rsquo;ils avaient eu le privil\u00e8ge de voyager aux sources du monde civilis\u00e9.<\/p>\n<figure id=\"attachment_7610\" aria-describedby=\"caption-attachment-7610\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg\" data-lightbox=\"gal[7580]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7610\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/193263-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?fit=675%2C800&amp;ssl=1\" data-orig-size=\"675,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;DMC-LX100&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1470413811&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;10.9&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"193263-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?fit=253%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?fit=665%2C788&amp;ssl=1\" class=\"wp-image-7610\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?resize=600%2C711\" alt=\"\" width=\"600\" height=\"711\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?w=675&amp;ssl=1 675w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?resize=253%2C300&amp;ssl=1 253w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/193263-1.jpg?resize=152%2C180&amp;ssl=1 152w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-7610\" class=\"wp-caption-text\">Grand Tour &#8211; Rome &#8211;<br \/> Boite ronde en \u00e9caille, dessus incrust\u00e9 d&rsquo;une plaque en thuya sculpt\u00e9<br \/> Epoque d\u00e9but XIX.<br \/> (c) Galerie Jean Rey, Proantic.<\/figcaption><\/figure>\n<p>La pratique du Grand Tour devint moins fr\u00e9quente pendant les guerres de la\u00a0R\u00e9volution\u00a0et de l\u2019Empire. Le continent proche \u00e9tant interdit, les jeunes gens partirent donc plus loin, vers la\u00a0Gr\u00e8ce\u00a0et le Levant. Le Grand Tour reprit \u00e0 la\u00a0Restauration\u00a0sans conna\u00eetre toutefois la popularit\u00e9 du si\u00e8cle pr\u00e9c\u00e8dent.<\/p>\n<p>Le Grand Tour occasionnait la publication de nombreux livres de voyage et guides dont un des premiers utilis\u00e9 fut\u00a0<i>An Account of Some of the Statues, Bas-Reliefs, Drawings, and Pictures in Italy<\/i>\u00a0(1722), \u00e9crit par les peintres britanniques\u00a0Jonathan Richardson\u00a0(1665-1745) et son fils Jonathan Richardson le Jeune (1694-1771).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l&rsquo;origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes filles, des plus hautes classes de la soci\u00e9t\u00e9 europ\u00e9enne, britannique, allemande, mais aussi fran\u00e7aise, n\u00e9erlandaise, polonaise, scandinave, plus tardivement russe \u00e0 partir des ann\u00e9es 1760. La pratique, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":7602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[372],"tags":[],"class_list":["post-7580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abc-du-decor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l&#039;origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l&#039;origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-29T10:04:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-01T14:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931\"},\"headline\":\"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes\",\"datePublished\":\"2017-09-29T10:04:08+00:00\",\"dateModified\":\"2017-10-01T14:03:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\"},\"wordCount\":1516,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1\",\"articleSection\":[\"ABC du d\u00e9cor\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\",\"name\":\"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1\",\"datePublished\":\"2017-09-29T10:04:08+00:00\",\"dateModified\":\"2017-10-01T14:03:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931\"},\"description\":\"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l'origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1\",\"width\":1000,\"height\":757},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic","description":"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l'origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic","og_description":"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l'origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes","og_url":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2017-09-29T10:04:08+00:00","article_modified_time":"2017-10-01T14:03:20+00:00","og_image":[{"width":1000,"height":757,"url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","type":"image\/jpeg"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931"},"headline":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes","datePublished":"2017-09-29T10:04:08+00:00","dateModified":"2017-10-01T14:03:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/"},"wordCount":1516,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","articleSection":["ABC du d\u00e9cor"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/","url":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/","name":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","datePublished":"2017-09-29T10:04:08+00:00","dateModified":"2017-10-01T14:03:20+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931"},"description":"Le Grand Tour, \u00e9crit de la m\u00eame fa\u00e7on en anglais, est \u00e0 l'origine un long voyage en Europe effectu\u00e9 par les jeunes gens, et tr\u00e8s rarement les jeunes","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","width":1000,"height":757},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/grand-tour-voyage-de-noblesses-europeennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Le Grand Tour: le voyage de la noblesses europ\u00e9ennes"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/870544872d3e2c41c7f1af01215d0931","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2017\/09\/249100-1.jpg?fit=1000%2C757&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-1Yg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/7580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=7580"}],"version-history":[{"count":0,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/7580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/7602"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=7580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=7580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=7580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}