{"id":3799,"date":"2015-08-05T10:28:52","date_gmt":"2015-08-05T09:28:52","guid":{"rendered":"http:\/\/www.proantic.com\/magazine\/?p=3799"},"modified":"2017-12-15T11:05:50","modified_gmt":"2017-12-15T10:05:50","slug":"exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/","title":{"rendered":"Exposition Flamands et hollandais &#8211; Mus\u00e9e des beaux-arts de Nantes"},"content":{"rendered":"<p><strong><em>Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition s&rsquo;inscrit dans un cycle qui invite \u00e0 (re)d\u00e9couvrir leurs collections pendant la p\u00e9riode de travaux d&rsquo;extension et de r\u00e9novation de ce mus\u00e9e.<\/em><\/strong><\/p>\n<p>Le mus\u00e9e des Beaux-Arts de Nantes pr\u00e9sente une s\u00e9lection de soixante-cinq chefs-d\u2019\u0153uvre, principalement du Si\u00e8cle d\u2019or, \u00e0 l\u2019occasion de la publication du catalogue in\u00e9dit des collections flamande et hollandaise, de la grande peinture d\u2019histoire aux petits tableaux de cabinet si appr\u00e9ci\u00e9s des marchands et des bourgeois des anciens Pays-Bas.<\/p>\n<figure id=\"attachment_3800\" aria-describedby=\"caption-attachment-3800\" style=\"width: 376px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3800\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/djfkir\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?fit=376%2C503&amp;ssl=1\" data-orig-size=\"376,503\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Celine&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438772569&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"FLINCK Govert, Portrait d&amp;rsquo;une fillette en Flore\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;FLINCK Govert, Portrait d&amp;rsquo;une fillette en Flore, Huile sur toile&lt;br \/&gt;\n \u00a9 RMN -Photographie : G. BLOT&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?fit=224%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?fit=376%2C503&amp;ssl=1\" class=\"size-full wp-image-3800\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?resize=376%2C503\" alt=\"FLINCK Govert, Portrait d'une fillette en Flore, Huile sur toile  \u00a9 RMN -Photographie : G. BLOT\" width=\"376\" height=\"503\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?w=376&amp;ssl=1 376w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/djfkir.jpg?resize=224%2C300&amp;ssl=1 224w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/a><figcaption id=\"caption-attachment-3800\" class=\"wp-caption-text\"><strong>FLINCK Govert, Portrait d&rsquo;une fillette en Flore, Huile sur toile<\/strong><br \/>\u00a9 RMN -Photographie : G. BLOT<\/figcaption><\/figure>\n<p>Cet important ensemble de peintures fut principalement r\u00e9uni au XIXe si\u00e8cle, essentiellement gr\u00e2ce aux envois de l\u2019\u00c9tat (Rubens, Brueghel) apr\u00e8s la cr\u00e9ation du Mus\u00e9e des beaux-arts, mais surtout avec l&rsquo;acquisition en 1810 par la ville de la collection de Fran\u00e7ois Cacault, v\u00e9ritable noyau fondateur des collections anciennes puisqu&rsquo;elle compte plus de 170 tableaux flamands et hollandais.<\/p>\n<p>Les sections th\u00e9matiques permettent de c\u00e9l\u00e9brer, en miroir entre la Flandre et la Hollande, ces genres nouveaux dans lesquels se sp\u00e9cialis\u00e8rent les peintres : portraits (Pourbus, Voet), paysages (Fouqui\u00e8res, Lytens), marines, sc\u00e8nes de genre (Droochsloot, Wouwerman) et natures mortes (Claesz, Coninck). Les collections du mus\u00e9e rassemblent les plus grands artistes du 16<sup>e<\/sup> au 18<sup>e<\/sup> si\u00e8cle, de Jan Brueghel \u00e0 Rubens, en passant par de remarquables \u00e9l\u00e8ves de Rembrandt (Govert Flinck, Ju\u0308rgen Ovens).<\/p>\n<figure id=\"attachment_3801\" aria-describedby=\"caption-attachment-3801\" style=\"width: 566px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3801\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/ghu\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?fit=566%2C370&amp;ssl=1\" data-orig-size=\"566,370\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Celine&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438772935&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gijsbrecht Leytens, Paysage d&amp;rsquo;hiver avec gitans et patineurs\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Gijsbrecht Leytens, Paysage d&amp;rsquo;hiver avec gitans et patineurs, Huile sur bois,&lt;br \/&gt;\n \u00a9 RMN -Photographie : G. BLOT&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?fit=300%2C196&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?fit=566%2C370&amp;ssl=1\" class=\"size-full wp-image-3801\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?resize=566%2C370\" alt=\"Gijsbrecht Leytens, Paysage d'hiver avec gitans et patineurs, Huile sur bois,  \u00a9 RMN -Photographie : G. BLOT\" width=\"566\" height=\"370\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?w=566&amp;ssl=1 566w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?resize=300%2C196&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/ghu.jpg?resize=230%2C150&amp;ssl=1 230w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/a><figcaption id=\"caption-attachment-3801\" class=\"wp-caption-text\"><strong>Gijsbrecht Leytens, Paysage d&rsquo;hiver avec gitans et patineurs, Huile sur bois<\/strong>,<br \/>\u00a9 RMN -Photographie : G. BLOT<\/figcaption><\/figure>\n<p><span style=\"color: #ff0000\"><strong>Parcours de l&rsquo;exposition <\/strong><\/span><\/p>\n<p><strong>\u00c9mancipation des genres : portraits, sc\u00e8nes de genre, paysages, natures mortes .<\/strong><\/p>\n<p>L&rsquo;histoire de la peinture n\u00e9erlandaise commence v\u00e9ritablement avec l&rsquo;invention de la peinture \u00e0 l&rsquo;huile. Port\u00e9e d\u00e8s ses d\u00e9buts au XVe si\u00e8cle \u00e0 un haut degr\u00e9 de perfection par Jan Van Eyck (Maaseik ? vers 1390 \u2013 Bruges, 1441), elle conna\u00eet un v\u00e9ritable d\u00e9clin vers 1700, lorsque le r\u00f4le politique des Pays-Bas ne devient qu&rsquo;annexe sur l\u2019\u00e9chiquier europ\u00e9en. La peinture produite dans l&rsquo;Europe du Nord avant le XVe si\u00e8cle est essentiellement religieuse.<\/p>\n<p>Dans ces tableaux religieux, la pr\u00e9sence des donateurs et des objets annoncent d\u00e9j\u00e0 la v\u00e9ritable naissance des \u00ab genres \u00bb aux si\u00e8cles suivants. La nouvelle technique de la peinture \u00e0 l&rsquo;huile, autorise les d\u00e9tails les plus pr\u00e9cis et les plus raffin\u00e9s. Portraits, paysages, natures mortes et sc\u00e8nes de genre deviennent alors des genres artistiques ind\u00e9pendants.<\/p>\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"665\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/sgrcdsYsC4w?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<p><strong> Peinture d&rsquo;histoire : l&rsquo;influence de Rubens et Rembrandt <\/strong><\/p>\n<p>En Italie, l&rsquo;esprit de la Contre-R\u00e9forme catholique, en r\u00e9action \u00e0 la mont\u00e9e du protestantisme, suscite une forte reprise de la peinture.\u00a0<span style=\"line-height: 1.5\">L&rsquo;art id\u00e9al des Carrache et le clair obscur du Caravage r\u00e9volutionnent la peinture, influen\u00e7ant durablement Rubens. Le retour du ma\u00eetre flamand \u00e0 Anvers en 1608, apr\u00e8s un long s\u00e9jour italien, marque le d\u00e9but d&rsquo;une nouvelle \u00e8re picturale. <\/span><\/p>\n<p><span style=\"line-height: 1.5\">Du c\u00f4t\u00e9 des Provinces-Unies, seule la figure de Rembrandt semble rivaliser quelques ann\u00e9es plus tard, avec une originalit\u00e9 qui lui reste propre et que l&rsquo;on retrouve chez certains peintres de son atelier (Ovens, Moyaert).<\/span><\/p>\n<figure id=\"attachment_3802\" aria-describedby=\"caption-attachment-3802\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3802\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/dkleo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&amp;ssl=1\" data-orig-size=\"580,572\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Celine&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438773244&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme, mus\u00e9e des Beaux-Arts de Nantes &amp;#8211; \u00a9 RMN -Photographie : G. BLOT&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=300%2C296&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&amp;ssl=1\" class=\"size-full wp-image-3802\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?resize=580%2C572\" alt=\"Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme, mus\u00e9e des Beaux-Arts de Nantes - \u00a9 RMN -Photographie : G. BLOT\" width=\"580\" height=\"572\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?resize=300%2C296&amp;ssl=1 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><figcaption id=\"caption-attachment-3802\" class=\"wp-caption-text\"><strong>Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme, mus\u00e9e des Beaux-Arts de Nantes<\/strong> &#8211; \u00a9 RMN -Photographie : G. BLOT<\/figcaption><\/figure>\n<p><strong>Le portrait : entre soci\u00e9t\u00e9 et intimit\u00e9 <\/strong><\/p>\n<p>Au XVe si\u00e8cle, les pieuses figures de donateurs des tableaux religieux prennent leur ind\u00e9pendance pour devenir d&rsquo;orgueilleux portraits autonomes. La tendance tr\u00e8s r\u00e9aliste des portraits flamands (Pourbus) fixe pour la post\u00e9rit\u00e9 les traits d&rsquo;un personnage, l&rsquo;inscrivant dans l&rsquo;histoire prestigieuse de sa famille (Voet). L&rsquo;abondance de portraits hollandais au Si\u00e8cle d\u2019Or s\u2019explique quant \u00e0 elle par l\u2019extraordinaire d\u00e9veloppement du commerce qui fait des Pays-Bas du nord une des grandes puissances \u00e9conomiques mondiales. Les peintres r\u00e9pondent aux attentes de leurs commanditaires en multipliant les variantes, des portraits individuels (Ravenstein) aux portraits collectifs des familles (Palamedes) ou de guildes.<\/p>\n<p>Rembrandt et ses \u00e9l\u00e8ves se d\u00e9marquent encore une fois des courants traditionnels : les visages de vieillards outrageusement frip\u00e9s (Portrait d&rsquo;homme), les costumes fantasques et les paysages \u00e9tranges (Flinck) accusent la rupture avec les portraits officiels.<\/p>\n<p><strong>Nature morte : opulence flamande et festin monochrome hollandais<\/strong><\/p>\n<p>Le succ\u00e8s des natures mortes entra\u00eene la cr\u00e9ation de sous genres ind\u00e9pendants et d\u00e9coratifs comme les tableaux de bouquets de fleurs (Goswin, Seghers) ou encore d&rsquo;animaux (van Boucle). Entre 1620 et 1640, sous l\u2019influence de la bourgeoisie protestante, le th\u00e8me de la \u00ab table servie \u00bb (pour le d\u00e9jeuner, le d\u00eener, une collation) est le th\u00e9\u00e2tre d&rsquo;une petite r\u00e9volution plastique : le \u00ab festin monochrome \u00bb (Claesz, de Stomme) \u00e0 la composition resserr\u00e9e et \u00e0 la palette tr\u00e8s sobre. Tandis qu&rsquo;\u00e0 l&rsquo;oppos\u00e9, en Flandre, s&rsquo;affirme l&rsquo;opulence du baroque dans une fonction purement d\u00e9corative, avec de grandes compositions ostentatoires et somptueuses (Koninck).<\/p>\n<figure id=\"attachment_3803\" aria-describedby=\"caption-attachment-3803\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3803\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/dkfoe\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?fit=480%2C320&amp;ssl=1\" data-orig-size=\"480,320\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Celine&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1438773929&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Jan I Brueghel dit Brueghel de Velours, Sc\u00e8ne fluviale ou le d\u00e9barquement\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Jan I Brueghel dit Brueghel de Velours, Sc\u00e8ne fluviale ou le d\u00e9barquement&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?fit=480%2C320&amp;ssl=1\" class=\"wp-image-3803 size-full\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?resize=480%2C320\" alt=\"Jan I Brueghel dit Brueghel de Velours, Sc\u00e8ne fluviale ou le d\u00e9barquement\" width=\"480\" height=\"320\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkfoe.jpg?resize=192%2C128&amp;ssl=1 192w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><figcaption id=\"caption-attachment-3803\" class=\"wp-caption-text\"><strong>Jan I Brueghel dit Brueghel de Velours, Sc\u00e8ne fluviale ou le d\u00e9barquement.<\/strong>\u00a0 \u00a9 RMN<\/figcaption><\/figure>\n<p><strong style=\"line-height: 1.5\">Le paysage : entre vision r\u00e9aliste et id\u00e9al<\/strong><\/p>\n<p>Les paysages du XVIIe si\u00e8cle adoptent un point de vue \u00e9lev\u00e9, panoramique (Van Alsloot), ainsi qu&rsquo;une perspective atmosph\u00e9rique rendue possible gr\u00e2ce \u00e0 la subtilit\u00e9 de la peinture \u00e0 l&rsquo;huile (Brueghel de Velours, Fouqui\u00e8res, Momper).<\/p>\n<p>Une sp\u00e9cialisation croissante des peintres est accompagn\u00e9e de la cr\u00e9ation de sous genres : paysages ruraux (Braedel), paysages de neige (Leytens), marines (Vlieger), etc. \u00c0 la fin du si\u00e8cle, les peintres hollandais italianisants (Appelman, Asselijn, Breenbergh) renouvellent le genre, m\u00ealant dans une m\u00eame lumi\u00e8re dor\u00e9e cr\u00e9pusculaire leur approche naturaliste et la vision id\u00e9ale d&rsquo;une Arcadie perdue<\/p>\n<p><strong>La peinture de genre : verve satirique et d\u00e9lectation pittoresque <\/strong><\/p>\n<p>La peinture de genre s&rsquo;illustre par des sc\u00e8nes de la vie quotidienne (vie domestique, travail et divertissements), dont les personnages sont anonymes. Au XVIIe si\u00e8cle, les sc\u00e8nes paysannes constituent un r\u00e9pertoire privil\u00e9gi\u00e9 de la peinture de genre. Dans une tradition satirique et morale initi\u00e9e par les kermesses paysannes et les danses villageoises de Pieter Brueghel l\u2019Ancien, elles d\u00e9peignent des comportements peu raffin\u00e9s, parfois \u00e0 la limite de la paillardise.<\/p>\n<p>Dans les Pays-Bas du nord, la peinture de genre conna\u00eet un d\u00e9veloppement sans pr\u00e9c\u00e9dent, avec une sp\u00e9cialisation en sous genres : joyeuses compagnies (Brakenburg), int\u00e9rieurs et ext\u00e9rieurs avec des occupations domestiques (Van Buesem, Van Bloemen, Van Oost) ou militaires (Wouwerman).<\/p>\n<p><span style=\"color: #ff0000\">En savoir plus:<\/span><\/p>\n<p><b>\u00a0Ch\u00e2teau des ducs de Bretagne, Nantes (jusqu&rsquo;au 30 ao\u00fbt 2015)<\/b><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Qtl0MQa6E2\"><p><a href=\"https:\/\/www.chateaunantes.fr\/\">Accueil<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Accueil\u00a0\u00bb &#8212; Ch\u00e2teau des ducs de Bretagne | Mus\u00e9e d\u2019histoire de Nantes\" src=\"https:\/\/www.chateaunantes.fr\/embed\/#?secret=3yaFkCrcj5#?secret=Qtl0MQa6E2\" data-secret=\"Qtl0MQa6E2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition s&rsquo;inscrit dans un cycle qui invite \u00e0 (re)d\u00e9couvrir leurs collections pendant la p\u00e9riode de travaux d&rsquo;extension et de r\u00e9novation de ce mus\u00e9e. Le mus\u00e9e des Beaux-Arts de Nantes pr\u00e9sente une s\u00e9lection de soixante-cinq [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-3799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expositions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-05T09:28:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-15T10:05:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"headline\":\"Exposition Flamands et hollandais &#8211; Mus\u00e9e des beaux-arts de Nantes\",\"datePublished\":\"2015-08-05T09:28:52+00:00\",\"dateModified\":\"2017-12-15T10:05:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\"},\"wordCount\":1184,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1\",\"articleSection\":[\"Expositions\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\",\"name\":\"Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1\",\"datePublished\":\"2015-08-05T09:28:52+00:00\",\"dateModified\":\"2017-12-15T10:05:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"description\":\"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1\",\"width\":580,\"height\":572,\"caption\":\"Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme, mus\u00e9e des Beaux-Arts de Nantes - \u00a9 RMN -Photographie : G. BLOT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposition Flamands et hollandais &#8211; Mus\u00e9e des beaux-arts de Nantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic","description":"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/","og_locale":"fr_FR","og_type":"article","og_title":"Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic","og_description":"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition","og_url":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2015-08-05T09:28:52+00:00","article_modified_time":"2017-12-15T10:05:50+00:00","og_image":[{"width":580,"height":572,"url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","type":"image\/jpeg"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"headline":"Exposition Flamands et hollandais &#8211; Mus\u00e9e des beaux-arts de Nantes","datePublished":"2015-08-05T09:28:52+00:00","dateModified":"2017-12-15T10:05:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/"},"wordCount":1184,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","articleSection":["Expositions"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/","url":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/","name":"Exposition Flamands et hollandais - Mus\u00e9e des beaux-arts de Nantes Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","datePublished":"2015-08-05T09:28:52+00:00","dateModified":"2017-12-15T10:05:50+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"description":"Le Ch\u00e2teau des ducs de Bretagne accueille les chefs-d\u2019\u0153uvre des collections flamande et hollandaise du mus\u00e9e des Beaux-Arts de Nantes. Cette exposition","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","width":580,"height":572,"caption":"Fran\u00e7ois II Pourbus (1569-1622), Portrait de femme, mus\u00e9e des Beaux-Arts de Nantes - \u00a9 RMN -Photographie : G. BLOT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/exposition-flamands-et-hollandais-musee-des-beaux-arts-de-nantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Exposition Flamands et hollandais &#8211; Mus\u00e9e des beaux-arts de Nantes"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2015\/08\/dkleo.jpg?fit=580%2C572&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-Zh","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/3799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=3799"}],"version-history":[{"count":0,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/3799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/3802"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=3799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=3799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=3799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}