{"id":18329,"date":"2026-04-24T14:10:29","date_gmt":"2026-04-24T13:10:29","guid":{"rendered":"https:\/\/www.proantic.com\/magazine\/?p=18329"},"modified":"2026-04-24T14:10:29","modified_gmt":"2026-04-24T13:10:29","slug":"sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/","title":{"rendered":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris"},"content":{"rendered":"\n<p>Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau, excellence des savoir-faire et attachement au patrimoine, la famille Rothschild noue un lien unique avec S\u00e8vres, une manufacture embl\u00e9matique et vivante depuis 1740.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De S\u00e8vres aux Rothschild : histoire d\u2019une fascination<\/h2>\n\n\n\n<p>Au sein de la famille Rothschild, les collections se cr\u00e9ent et se transmettent de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration. Gr\u00e2ce \u00e0 leur g\u00e9n\u00e9rosit\u00e9, nombre de ces tr\u00e9sors ont rejoint les collections publiques fran\u00e7aises et de grands mus\u00e9es internationaux.<\/p>\n\n\n\n<p>De Francfort \u00e0 Paris, en passant par Vienne, Naples ou Londres, les Rothschild ont r\u00e9uni parmi les plus spectaculaires porcelaines de S\u00e8vres du XVIII\u1d49 si\u00e8cle : vases aux formes de vaisseaux, d\u2019animaux ou d\u2019architectures, aux couleurs \u00e9clatantes et aux d\u00e9cors virtuoses. Pr\u00e9sent\u00e9es dans une sc\u00e9nographie immersive, ces \u0153uvres dialoguent avec des archives in\u00e9dites et des int\u00e9rieurs reconstitu\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"433\" data-attachment-id=\"18338\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/exposition-rothschild-mobilier-national-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?fit=2362%2C1539&amp;ssl=1\" data-orig-size=\"2362,1539\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D1X&quot;,&quot;caption&quot;:&quot;cr\\u00c8dits: Garniture de trois vases, dont un vase de \\u00b4?milieu?\\u00aa ovale \\u2021 boucs et raisins et deux vases \\u00b4?de c\\u00d9t\\u00c8?\\u00aa \\u2021 t\\u00cdtes de bouc \\r\\rManufacture de S\\u00cbvres \\rSous la direction de Jean-Jacques Bachelier \\rVers 1767 \\rPorcelaine tendre \\rS\\u00cbvres, mus\\u00c8e national de C\\u00c8ramique, inv. MNC 28583.1 \\u2021 3 \\r\\u00a9 GrandPalaisRmn (S\\u00cbvres - Manufacture et mus\\u00c8e nationaux) \/ Martine Beck-Coppola&quot;,&quot;created_timestamp&quot;:&quot;1095681434&quot;,&quot;copyright&quot;:&quot;\\u00a9 Photo Martine Beck Coppola&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;2&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?fit=300%2C195&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?fit=665%2C433&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=665%2C433&#038;ssl=1\" alt=\"\" class=\"wp-image-18338\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=1024%2C667&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=300%2C195&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=768%2C500&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=1536%2C1001&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?resize=2048%2C1334&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?w=1330&amp;ssl=1 1330w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/exposition-rothschild-mobilier-national-1.jpg?w=1995&amp;ssl=1 1995w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><\/figure>\n\n\n\n<p>R\u00e9unissant pour la premi\u00e8re fois les Manufactures nationales \u2013 S\u00e8vres &amp; Mobilier national et l\u2019Acad\u00e9mie des beaux-arts, propri\u00e9taire de la Villa Ephrussi de Rothschild, l\u2019exposition propose un parcours en neuf sections, introduit par B\u00e9atrice Ephrussi de Rothschild. Elle retrace l\u2019histoire de ces chefs-d\u2019\u0153uvre, tout en \u00e9voquant les spoliations subies par la famille, gr\u00e2ce \u00e0 des pr\u00eats exceptionnels de grandes institutions fran\u00e7aises et internationales.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"741\" data-attachment-id=\"18337\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/671743744_1420608473438819_3418888127299357273_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?fit=640%2C741&amp;ssl=1\" data-orig-size=\"640,741\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?fit=259%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?fit=640%2C741&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?resize=640%2C741&#038;ssl=1\" alt=\"\" class=\"wp-image-18337\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/671743744_1420608473438819_3418888127299357273_n.jpg?resize=259%2C300&amp;ssl=1 259w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>LE MARCH\u00c9 DE L\u2019ART DU \u00ab VIEUX S\u00c8VRES \u00bb<\/p>\n\n\n\n<p>La R\u00e9volution fran\u00e7aise dispersa sur le march\u00e9 de l\u2019art europ\u00e9en des milliers d\u2019objets d\u2019art. Les collectionneurs anglais, dont le futur roi George IV, furent les premiers \u00e0 retrouver le go\u00fbt pour la porcelaine de S\u00e8vres et rassembl\u00e8rent dans leurs collections les plus exceptionnelles cr\u00e9ations de la manufacture. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"387\" height=\"580\" data-attachment-id=\"18336\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/capture-decran-2026-04-24-113337\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?fit=387%2C580&amp;ssl=1\" data-orig-size=\"387,580\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vase \u00ab \u00e0 t\u00eates d\u2019\u00e9l\u00e9phants \u00bb&lt;br \/&gt;\nManufacture de S\u00e8vres&lt;br \/&gt;\nAttribu\u00e9 \u00e0 Jean-Louis Morin (peintre)&lt;br \/&gt;\nVers 1760&lt;br \/&gt;\nPorcelaine tendre&lt;br \/&gt;\nWaddesdon Manor&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?fit=387%2C580&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?resize=387%2C580&#038;ssl=1\" alt=\"\" class=\"wp-image-18336\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?w=387&amp;ssl=1 387w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113337.png?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 387px) 100vw, 387px\" \/><\/a><figcaption class=\"wp-element-caption\">Vase \u00ab \u00e0 t\u00eates d\u2019\u00e9l\u00e9phants \u00bb<br>Manufacture de S\u00e8vres<br>Attribu\u00e9 \u00e0 Jean-Louis Morin (peintre)<br>Vers 1760<br>Porcelaine tendre<br>Waddesdon Manor<\/figcaption><\/figure>\n<\/div>\n\n\n<p>En France, l\u2019attrait pour le \u00ab vieux S\u00e8vres \u00bb de l\u2019Ancien R\u00e9gime rena\u00eet dans les ann\u00e9es 1820. James et Betty de Rothschild sont alors install\u00e9s rue Laffitte, \u00e0 quelques pas de l\u2019h\u00f4tel Drouot, qui ouvre ses portes en 1852. Celui-ci marque le d\u00e9but d\u2019une fr\u00e9n\u00e9sie des ench\u00e8res parisiennes dans laquelle la famille Rothschild joue un r\u00f4le capital. Une course \u00e0 la \u00ab curiosit\u00e9 \u00bb anime le Tout-Paris. Les premi\u00e8res g\u00e9n\u00e9rations de la famille, en France comme en Angleterre et en Autriche, participent aux grandes ventes telles celles des collections du comte de Pembroke, de L\u00e9opold Double ou encore du prince Demidoff et y acqui\u00e8rent des S\u00e8vres. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"770\" data-attachment-id=\"18339\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/672672621_1420608103438856_296821755731770578_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?fit=640%2C770&amp;ssl=1\" data-orig-size=\"640,770\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?fit=249%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?fit=640%2C770&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?resize=640%2C770&#038;ssl=1\" alt=\"\" class=\"wp-image-18339\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672621_1420608103438856_296821755731770578_n.jpg?resize=249%2C300&amp;ssl=1 249w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Les prix s\u2019envolent et le connoisseur ship se d\u00e9veloppe, tandis que le commerce des faux prend de l\u2019ampleur. Le march\u00e9 londonien n\u2019est pas en reste et Alphonse, Gustave ou B\u00e9atrice de Rothschild ach\u00e8tent certains de leurs chefs-d\u2019\u0153uvre dans les ventes organis\u00e9es par Christie, Manson &amp; Woods, celles des collections de Ralph Bernal en 1855 ou de Lord Revelstoke en 1893. Au c\u0153ur de ce syst\u00e8me, le r\u00e9seau des marchands tels que Charles Mannheim, Henri Stettiner, L\u00e9on Gauchez ou la c\u00e9l\u00e8bre dynastie des Wertheimer joue un r\u00f4le capital dans le d\u00e9veloppement de leurs collections.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"332\" data-attachment-id=\"18332\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/capture-decran-2026-04-24-111459\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?fit=867%2C433&amp;ssl=1\" data-orig-size=\"867,433\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Garniture de quatre vases : paire de pots-pourris&lt;br \/&gt;\n\u00ab \u00e0 jour \u00bb en troisi\u00e8me grandeur et paire de vases \u00ab Duplessis \u00bb&lt;br \/&gt;\nManufacture de Vincennes&lt;br \/&gt;\nCharles Nicolas Dodin (peintre, actif de 1754 \u00e0 1803)&lt;br \/&gt;\nAndr\u00e9 Vincent Vielliard (peintre, actif de 1752 \u00e0 1790)&lt;br \/&gt;\n1755&lt;br \/&gt;\nPorcelaine tendre&lt;br \/&gt;\nBruxelles, collection particuli\u00e8re&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?fit=300%2C150&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?fit=665%2C332&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?resize=665%2C332&#038;ssl=1\" alt=\"\" class=\"wp-image-18332\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?w=867&amp;ssl=1 867w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-111459.png?resize=768%2C384&amp;ssl=1 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Garniture de quatre vases : paire de pots-pourris<br>\u00ab \u00e0 jour \u00bb en troisi\u00e8me grandeur et paire de vases \u00ab Duplessis \u00bb<br>Manufacture de Vincennes<br>Charles Nicolas Dodin (peintre, actif de 1754 \u00e0 1803)<br>Andr\u00e9 Vincent Vielliard (peintre, actif de 1752 \u00e0 1790)<br>1755<br>Porcelaine tendre<br>Bruxelles, collection particuli\u00e8re<\/figcaption><\/figure>\n\n\n\n<p>LA VILLA \u00ceLE-DE-FRANCE<\/p>\n\n\n\n<p>Alors qu\u2019elle se rend presque chaque ann\u00e9e sur la C\u00f4te d\u2019Azur, o\u00f9 vient se r\u00e9fugier en hiver toute l\u2019aristocratie europ\u00e9enne, B\u00e9atrice Ephrussi fait l\u2019acquisition en 1906 d\u2019un terrain de huit hectares, qui n\u2019est alors gu\u00e8re plus qu\u2019un \u00e9peron rocheux situ\u00e9 sur les cimes du cap Ferrat, un petit village de p\u00eacheurs devenu aujourd\u2019hui la \u00ab presqu\u2019\u00eele des Milliardaires \u00bb. Construite en cinq ans, la villa, qu\u2019elle baptise \u00cele-de-France, est meubl\u00e9e en suivant le go\u00fbt \u00e9clectique de sa propri\u00e9taire : primitifs italiens, paravents japonais, mobilier de Joseph, Jacob, Delanois ou Dubois mais \u00e9galement tapis de la Savonnerie et porcelaine de S\u00e8vres, qu\u2019elle collectionne avec passion jusqu\u2019aux derniers mois de sa vie. La baronne d\u00e9cide, avant sa mort en 1934, de l\u00e9guer l\u2019\u00e9difice et l\u2019int\u00e9gralit\u00e9 de sa collection d\u2019art, soit pr\u00e8s de 6 000 objets, \u00e0 l\u2019Acad\u00e9mie des beaux arts, en souvenir de son p\u00e8re Alphonse qui en \u00e9tait membre. Les collections de ce \u00ab ch\u00e2teau Rothschild \u00bb de bord de mer, ouvert au public depuis 1938, sont encore largement m\u00e9connues du public.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"462\" data-attachment-id=\"18333\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/capture-decran-2026-04-24-113303\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?fit=869%2C604&amp;ssl=1\" data-orig-size=\"869,604\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?fit=300%2C209&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?fit=665%2C462&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?resize=665%2C462&#038;ssl=1\" alt=\"\" class=\"wp-image-18333\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?w=869&amp;ssl=1 869w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?resize=300%2C209&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113303.png?resize=768%2C534&amp;ssl=1 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><\/figure>\n\n\n\n<p><strong>La vie en rose : le triomphe du \u00ab cama\u00efeu carmin \u00bb<\/strong><\/p>\n\n\n\n<p>B\u00e9atrice Ephrussi a r\u00e9uni un ensemble exceptionnel de porcelaines peintes en cama\u00efeu carmin. Ce d\u00e9cor, \u00e9labor\u00e9 \u00e0 partir d\u2019or, pouvait pr\u00e9senter des nuances subtiles allant du rose p\u00e2le au rouge violac\u00e9. Appliqu\u00e9 sur les pi\u00e8ces destin\u00e9es \u00e0 la toilette ou \u00e0 la table, il est embl\u00e9matique des d\u00e9buts de la manufacture, alors situ\u00e9e \u00e0 Vincennes, avant d\u2019\u00eatre d\u00e9plac\u00e9e \u00e0 S\u00e8vres en 1756. L\u2019engouement pour ce d\u00e9cor dans les ann\u00e9es 1750 a \u00e9t\u00e9 favoris\u00e9 par les achats de clients importants tels que le roi Louis XV et la marquise de Pompadour. Le peintre Fran\u00e7ois Boucher fut le principal fournisseur des mod\u00e8les de ces d\u00e9cors, compos\u00e9s de paysages, de jeux d\u2019enfants ou de fleurs. Les collections de la baronne Ephrussi t\u00e9moignent de son go\u00fbt encyclop\u00e9dique jusque dans ce domaine, aussi bien par la vari\u00e9t\u00e9 des teintes, des services et des sources d\u2019inspiration comme en t\u00e9moigne un gobelet peint d\u2019apr\u00e8s une sc\u00e8ne de chasse de Jean-Baptiste Oudry.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"432\" data-attachment-id=\"18334\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/capture-decran-2026-04-24-113228\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?fit=698%2C453&amp;ssl=1\" data-orig-size=\"698,453\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vases Hollandais&lt;br \/&gt;\nPaire de vases \u00ab hollandois \u00bb, deuxi\u00e8me grandeur&lt;br \/&gt;\nManufacture de Vincennes&lt;br \/&gt;\nCharles Nicolas Dodin (peintre, actif de 1754 \u00e0 1803)&lt;br \/&gt;\n1756&lt;br \/&gt;\nPorcelaine tendre&lt;br \/&gt;\nSaint-Jean-Cap-Ferrat, Villa et jardins Ephrussi de Rothschild&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?fit=300%2C195&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?fit=665%2C432&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?resize=665%2C432&#038;ssl=1\" alt=\"\" class=\"wp-image-18334\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?w=698&amp;ssl=1 698w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113228.png?resize=300%2C195&amp;ssl=1 300w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Vases Hollandais<br>Paire de vases \u00ab hollandois \u00bb, deuxi\u00e8me grandeur<br>Manufacture de Vincennes<br>Charles Nicolas Dodin (peintre, actif de 1754 \u00e0 1803)<br>1756<br>Porcelaine tendre<br>Saint-Jean-Cap-Ferrat, Villa et jardins Ephrussi de Rothschild<\/figcaption><\/figure>\n<\/div>\n\n\n<p>AU C\u0152UR DE LA MANUFACTURE DE S\u00c8VRES<\/p>\n\n\n\n<p>Fond\u00e9e en 1740, la manufacture de porcelaine \u00e9tait \u00e0 l\u2019origine install\u00e9e au ch\u00e2teau de Vincennes. Trop \u00e0 l\u2019\u00e9troit dans ce lieu peu adapt\u00e9 pour le d\u00e9veloppement de son activit\u00e9, elle d\u00e9m\u00e9nagea \u00e0 S\u00e8vres dans un nouveau b\u00e2timent \u00e0 l\u2019\u00e9t\u00e9 1756. D\u00e8s 1753, elle avait pris le nom de \u00ab manufacture royale \u00bb et connut un essor consid\u00e9rable au cours du XVIIIe si\u00e8cle. Sa recherche perp\u00e9tuelle d\u2019innovation donna naissance \u00e0 des objets d\u2019une grande virtuosit\u00e9, qui rejoignirent au si\u00e8cle suivant les collections de la famille Rothschild. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"809\" data-attachment-id=\"18340\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/676273748_1420606693438997_2833821512623805344_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?fit=638%2C809&amp;ssl=1\" data-orig-size=\"638,809\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?fit=237%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?fit=638%2C809&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?resize=638%2C809&#038;ssl=1\" alt=\"\" class=\"wp-image-18340\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?w=638&amp;ssl=1 638w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/676273748_1420606693438997_2833821512623805344_n.jpg?resize=237%2C300&amp;ssl=1 237w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>L\u2019exceptionnel patrimoine conserv\u00e9 dans les archives de la manufacture met en lumi\u00e8re les diff\u00e9rentes \u00e9tapes de la fabrication des porcelaines, de la cr\u00e9ation d\u2019une forme \u00e0 la r\u00e9alisation du d\u00e9cor. Les mod\u00e8les du XVIIIe si\u00e8cle sont aujourd\u2019hui encore mis au service des cr\u00e9ations et des r\u00e9\u00e9ditions propos\u00e9es par la manufacture, t\u00e9moins de la continuit\u00e9 de ces savoir-faire d\u2019exception. Cet espace invite en premier lieu \u00e0 plonger dans l\u2019univers des formes de la manufacture, dont l\u2019un des plus c\u00e9l\u00e8bres cr\u00e9ateurs fut Jean-Claude Duplessis. Pour leur conception, le pl\u00e2tre est un mat\u00e9riau de pr\u00e9dilection. Il est mis en \u0153uvre afin de cr\u00e9er des mod\u00e8les, qui servent de r\u00e9f\u00e9rence aux artisans, et de r\u00e9aliser des moules, qui mettent en forme la p\u00e2te.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?ssl=1\" data-lightbox=\"gal[18329]\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"779\" data-attachment-id=\"18343\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/672672306_1420608026772197_1737103979841777515_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?fit=640%2C779&amp;ssl=1\" data-orig-size=\"640,779\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?fit=246%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?fit=640%2C779&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?resize=640%2C779&#038;ssl=1\" alt=\"\" class=\"wp-image-18343\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/672672306_1420608026772197_1737103979841777515_n.jpg?resize=246%2C300&amp;ssl=1 246w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Mille et un d\u00e9cors<\/h2>\n\n\n\n<p>Les d\u00e9cors r\u00e9alis\u00e9s \u00e0 S\u00e8vres au XVIIIe si\u00e8cle t\u00e9moignent de l\u2019exceptionnelle cr\u00e9ativit\u00e9 de ses artistes et et de ses artisans. Ils sont sublim\u00e9s par une palette de couleurs vari\u00e9es et souvent rehauss\u00e9s d\u2019une dorure g\u00e9n\u00e9reuse. Les motifs floraux et en particulier les roses occupent une place de choix. B\u00e9atrice Ephrussi semble avoir \u00e9t\u00e9 fascin\u00e9e par la richesse de ces motifs et sa collection constitue une v\u00e9ritable encyclop\u00e9die des ornements mis en \u0153uvre \u00e0 S\u00e8vres dans la seconde moiti\u00e9 du XVIIIe si\u00e8cle. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"551\" data-attachment-id=\"18335\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/capture-decran-2026-04-24-113210\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?fit=372%2C551&amp;ssl=1\" data-orig-size=\"372,551\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ensemble de gobelets et soucoupes&lt;br \/&gt;\nManufacture de S\u00e8vres&lt;br \/&gt;\nPorcelaine tendre&lt;br \/&gt;\nSaint-Jean-Cap-Ferrat, Villa et jardins&lt;br \/&gt;\nEphrussi de Rothschild&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?fit=203%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?fit=372%2C551&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?resize=372%2C551&#038;ssl=1\" alt=\"\" class=\"wp-image-18335\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?w=372&amp;ssl=1 372w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-113210.png?resize=203%2C300&amp;ssl=1 203w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/a><figcaption class=\"wp-element-caption\">Ensemble de gobelets et soucoupes<br>Manufacture de S\u00e8vres<br>Porcelaine tendre<br>Saint-Jean-Cap-Ferrat, Villa et jardins<br>Ephrussi de Rothschild<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Une \u00ab tassemania \u00bb s\u2019est empar\u00e9e de cette collectionneuse atypique, qui r\u00e9unit des centaines de petits objets pr\u00e9sentant des d\u00e9cors toujours diff\u00e9rents. Cette fascination pour les d\u00e9cors est \u00e9galement perceptible chez Edmond de Rothschild qui dans les ann\u00e9es 1880 envoya une certaine Madame de Zeppenfeld r\u00e9aliser des copies de d\u00e9cors conserv\u00e9s dans les archives de la manufacture de S\u00e8vres. Accueillie par Jules Champfleury, directeur de la manufacture, elle \u00e9tudia en particulier un exceptionnel livre-tarif du XVIIIe si\u00e8cle, recueil d\u2019ornements dans lequel les clients pouvaient effectuer leurs choix. Les dessins de Madame de Zeppenfeld, aujourd\u2019hui conserv\u00e9s \u00e0 Waddesdon Manor, sont r\u00e9unis pour la premi\u00e8re fois depuis la fin du XIXe si\u00e8cle avec leurs mod\u00e8les.<\/p>\n\n\n\n<p><strong>Exposition \u00ab S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris \u00bb, au Mobilier national, jusqu&rsquo;au 26 juillet 2026.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau, excellence des savoir-faire et attachement au patrimoine, la famille Rothschild noue un lien unique avec S\u00e8vres, une manufacture embl\u00e9matique et vivante depuis 1740. De S\u00e8vres aux Rothschild : [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":18344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-18329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expositions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-24T13:10:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1247\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\"},\"headline\":\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\",\"datePublished\":\"2026-04-24T13:10:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\"},\"wordCount\":1528,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1\",\"articleSection\":[\"Expositions\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\",\"name\":\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1\",\"datePublished\":\"2026-04-24T13:10:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\"},\"description\":\"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1\",\"width\":1247,\"height\":569},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic","description":"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic","og_description":"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,","og_url":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2026-04-24T13:10:29+00:00","og_image":[{"width":1247,"height":569,"url":"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png","type":"image\/png"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0"},"headline":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris","datePublished":"2026-04-24T13:10:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/"},"wordCount":1528,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1","articleSection":["Expositions"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/","url":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/","name":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1","datePublished":"2026-04-24T13:10:29+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0"},"description":"Plongez au c\u0153ur d\u2019une saga familiale hors du commun, o\u00f9 la passion pour la porcelaine de S\u00e8vres du XVIII\u1d49 si\u00e8cle traverse le temps. Entre amour du Beau,","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1","width":1247,"height":569},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/sevres-une-passion-rothschild-de-la-villa-ephrussi-a-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"S\u00e8vres, une passion Rothschild. De la Villa Ephrussi \u00e0 Paris"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-24-150644.png?fit=1247%2C569&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-4LD","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/18329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=18329"}],"version-history":[{"count":6,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/18329\/revisions"}],"predecessor-version":[{"id":18347,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/18329\/revisions\/18347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/18344"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=18329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=18329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=18329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}