{"id":17848,"date":"2025-08-16T15:04:59","date_gmt":"2025-08-16T14:04:59","guid":{"rendered":"https:\/\/www.proantic.com\/magazine\/?p=17848"},"modified":"2025-08-16T15:04:59","modified_gmt":"2025-08-16T14:04:59","slug":"jean-baptiste-greuze-les-dessins-du-louvre","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/","title":{"rendered":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre"},"content":{"rendered":"\n<p><strong>\u00c0 l&rsquo;occasion du trois-centi\u00e8me anniversaire de la naissance de l&rsquo;artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s&rsquo;associe au mus\u00e9e du Louvre pour lui rendre un hommage m\u00e9rit\u00e9.<\/strong> S\u00e9lectionn\u00e9es parmi la riche collection du Cabinet des dessins, trente feuilles du ma\u00eetre t\u00e9moignent \u00e0 la fois de son processus cr\u00e9atif et de sa volont\u00e9 de faire de certains de ses dessins les plus aboutis des \u0153uvres \u00e0 part enti\u00e8re destin\u00e9es \u00e0 une client\u00e8le d&rsquo;amateurs et de collectionneurs. Tous les th\u00e8mes de pr\u00e9dilection du ma\u00eetre sont ici illustr\u00e9s, sc\u00e8nes de genre, sujets \u00e0 connotation moralisatrice, t\u00eates d&rsquo;expression, portraits. Avec \u00e9vidence, ils soulignent combien Denis Diderot avait eu raison en consid\u00e9rant que Jean-Baptiste Greuze s&rsquo;\u00e9tait impos\u00e9 \u00e0 son si\u00e8cle en \u00ab \u00e2me d\u00e9licate et sensible <\/p>\n\n\n\n<p><strong>Exposition \u00ab Greuze, une palette d&rsquo;\u00e9motions \u00bb<\/strong> pr\u00e9sent\u00e9e \u00e0 l&rsquo;H\u00f4tel-Dieu &#8211; Mus\u00e9e de Tournus jusqu&rsquo;au 21 septembre 2025.<\/p>\n\n\n\n<p>\u00a0Editions\u00a0Mus\u00e9e de Tournus \/ Faton<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;occasion du trois-centi\u00e8me anniversaire de la naissance de l&rsquo;artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s&rsquo;associe au mus\u00e9e du Louvre pour lui rendre un hommage m\u00e9rit\u00e9. S\u00e9lectionn\u00e9es parmi la riche collection du Cabinet des dessins, trente feuilles du ma\u00eetre t\u00e9moignent \u00e0 la fois de son processus cr\u00e9atif et de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[575],"tags":[],"class_list":["post-17848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-catalogue-dexposition"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"\u00c0 l&#039;occasion du trois-centi\u00e8me anniversaire de la naissance de l&#039;artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s&#039;associe au mus\u00e9e du\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l&#039;occasion du trois-centi\u00e8me anniversaire de la naissance de l&#039;artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s&#039;associe au mus\u00e9e du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-16T14:04:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\"},\"headline\":\"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre\",\"datePublished\":\"2025-08-16T14:04:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\"},\"wordCount\":178,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1\",\"articleSection\":[\"Catalogue d'exposition\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\",\"name\":\"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1\",\"datePublished\":\"2025-08-16T14:04:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\"},\"description\":\"\u00c0 l'occasion du trois-centi\u00e8me anniversaire de la naissance de l'artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s'associe au mus\u00e9e du\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1\",\"width\":650,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic","description":"\u00c0 l'occasion du trois-centi\u00e8me anniversaire de la naissance de l'artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s'associe au mus\u00e9e du","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic","og_description":"\u00c0 l'occasion du trois-centi\u00e8me anniversaire de la naissance de l'artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s'associe au mus\u00e9e du","og_url":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2025-08-16T14:04:59+00:00","og_image":[{"width":650,"height":440,"url":"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png","type":"image\/png"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0"},"headline":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre","datePublished":"2025-08-16T14:04:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/"},"wordCount":178,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1","articleSection":["Catalogue d'exposition"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/","url":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/","name":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1","datePublished":"2025-08-16T14:04:59+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0"},"description":"\u00c0 l'occasion du trois-centi\u00e8me anniversaire de la naissance de l'artiste en 1725, la c\u00e9l\u00e8bre cit\u00e9 bourguignonne o\u00f9 il vit le jour s'associe au mus\u00e9e du","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1","width":650,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/jean-baptiste-greuze-les-dessins-du-louvre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"\u00a0Jean-Baptiste Greuze. Les dessins du Louvre"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/63707e8f4e7d0172de7ddde897688be0","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-16-153856.png?fit=650%2C440&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-4DS","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/17848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=17848"}],"version-history":[{"count":1,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/17848\/revisions"}],"predecessor-version":[{"id":17850,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/17848\/revisions\/17850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/17849"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=17848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=17848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=17848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}