{"id":16373,"date":"2024-01-30T14:52:19","date_gmt":"2024-01-30T13:52:19","guid":{"rendered":"https:\/\/www.proantic.com\/magazine\/?p=16373"},"modified":"2024-03-12T15:08:26","modified_gmt":"2024-03-12T14:08:26","slug":"boites-de-toilettes-en-vernis-rouge-et-or","status":"publish","type":"post","link":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/","title":{"rendered":"Bo\u00eetes de toilettes en vernis rouge et or"},"content":{"rendered":"\n<p><strong>Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros (cupidon) et V\u00e9nus. <\/strong>Autour des sc\u00e8nes principales, un riche d\u00e9cor de feuilles d\u2019acanthe, de corbeilles de fruits, d\u2019enroulements se d\u00e9ploient.<br>Travail probable de Guillaume Martin<br>Epoque Louis XIV (1710-1720)<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"444\" data-attachment-id=\"16374\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/1267557-main-65ad2b9971375\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bo\u00eetes de toilettes en vernis rouge et or.  (c) Galerie Pellat de Villedon, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Bo\u00eetes de toilettes en vernis rouge et or.&lt;br \/&gt;\n(c) Galerie Pellat de Villedon, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?fit=665%2C444&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?resize=665%2C444&#038;ssl=1\" alt=\"\" class=\"wp-image-16374\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-main-65ad2b9971375.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Bo\u00eetes de toilettes en vernis rouge et or.  (c) <a href=\"https:\/\/www.proantic.com\/galerie\/pellatdevilledon\/\">Galerie Pellat de Villedon<\/a>, Proantic<\/figcaption><\/figure>\n\n\n\n<p>La paire de bo\u00eetes de notre \u00e9tude est d\u2019une grande raret\u00e9 et rel\u00e8ve du domaine de l\u2019intime : ce sont des objets \u00e9mouvants, des t\u00e9moins du luxe de cette \u00e9poque. Il s\u2019agit de bo\u00eetes de toilettes, d\u00e9nomm\u00e9es \u00ab\u00a0carr\u00e9s\u00a0\u00bb dans les descriptions du XVIIIe si\u00e8cle, et malencontreusement souvent appel\u00e9es \u00e0 tort \u00ab\u00a0bo\u00eetes \u00e0 perruque\u00a0\u00bb.<\/p>\n\n\n\n<p> Ces bo\u00eetes, au tout d\u00e9but du XVIIIe si\u00e8cle, \u00e9taient soit sous forme de tombeau ou alors comme notre paire c\u2019est-\u00e0-dire rectangulaire avec le couvercle bomb\u00e9. Elles servaient \u00e0 ranger des brosses, peignes, \u00ab\u00a0flacons d\u2019eaux de senteurs\u00a0\u00bb, bijoux ou \u00e9l\u00e9ments de parure. Elles \u00e9taient alors r\u00e9alis\u00e9es par paire mais sont aujourd\u2019hui tr\u00e8s souvent retrouv\u00e9es seules. Elles \u00e9taient alors dispos\u00e9es de chaque c\u00f4t\u00e9 du miroir de toilette (miroir qui \u00e9tait pos\u00e9 sur une table r\u00e9serv\u00e9e \u00e0 cet effet). Ces bo\u00eetes reprenaient les formes des objets de toilettes en argent. Elles ne font pas dispara\u00eetre ces derniers et se m\u00e9langent apr\u00e8s leur cr\u00e9ation aux pi\u00e8ces d\u2019orf\u00e8vrerie. Le tableau conserv\u00e9 au Nelson-Atkins Museum of Art d\u2019apr\u00e8s Jean-Fran\u00e7ois de Troy permet ais\u00e9ment de comprendre leurs installations.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"997\" data-attachment-id=\"16375\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/1267557-65ad2bf774693\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?fit=800%2C1200&amp;ssl=1\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bo\u00eetes de toilettes en vernis rouge et or.  (c) Galerie Pellat de Villedon, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Bo\u00eetes de toilettes en vernis rouge et or.&lt;br \/&gt;\n(c) Galerie Pellat de Villedon, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?fit=665%2C997&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?resize=665%2C997&#038;ssl=1\" alt=\"\" class=\"wp-image-16375\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-65ad2bf774693.jpg?w=800&amp;ssl=1 800w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Bo\u00eetes de toilettes en vernis rouge et or.  (c) <a href=\"https:\/\/www.proantic.com\/galerie\/pellatdevilledon\/\">Galerie Pellat de Villedon,<\/a> Proantic<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ce qui en fait leur raret\u00e9 ce n\u2019est pas seulement que l&rsquo;ensemble soit complet, c\u2019est aussi leur datation. Le d\u00e9cor sur fond rouge si envoutant est marquant de la production des ann\u00e9es 1710-1720. En effet, il s\u2019agit des pr\u00e9misses de la production des bo\u00eetes en vernis europ\u00e9ens. C\u2019est pourquoi, les deux bo\u00eetes de notre \u00e9tude sont des objets historiques. Nous pouvons rapprocher les oeuvres de notre \u00e9tude \u00e0 celle conserv\u00e9e au Victoria and Albert Museum de cette m\u00eame \u00e9poque. Ce dit vernis permettait de concevoir des d\u00e9cors d\u2019une grande finesse. Il suffit de les observer dans les deux cartouches principaux \u00e0 l\u2019aide d\u2019une loupe pour appr\u00e9cier les paysages d\u00e9taill\u00e9s en arri\u00e8re-plan notamment tant les dessins sont complexes.<\/p>\n\n\n\n<p> La technique est la suivante : le b\u00e2ti de l\u2019objet recevait les couches color\u00e9es, le peintre en miniature ou le graveur r\u00e9alisaient l\u2019ornementation qui \u00e9tait recouverte d\u2019un mordant ; l\u2019or \u00e0 la feuille, en poudre ou sous forme de mixtion \u00e9tait appliqu\u00e9 et enfin le tout \u00e9tait recouvert de couches de laque translucide. Il s\u2019agit alors d\u2019une \u00ab\u00a0nouvelle mati\u00e8re\u00a0\u00bb, et les m\u00e9tiers li\u00e9s \u00e0 celles-ci se cr\u00e9ent. Dans cette production in\u00e9dite, ce sont les \u00ab\u00a0graveurs sur vernis\u00a0\u00bb qui sont autoris\u00e9s \u00e0 travailler l\u2019ornementation (les conventions ne permettant pas \u00e0 d\u2019autres corps de m\u00e9tier d\u2019exp\u00e9rimenter ce savoir-faire). Ainsi, la profession et la technique se d\u00e9veloppent. L\u2019\u00e9volution ira dans les ann\u00e9es 1730 vers l\u2019imitation des laques asiatiques. Nous abandonnons les d\u00e9cors \u00ab\u00a0fran\u00e7ais\u00a0\u00bb comme pr\u00e9sent\u00e9s sur notre paire de bo\u00eetes pour pr\u00e9f\u00e9rer celles \u00e9voquant l\u2019extr\u00eame Orient.\u00a0 Elles jouissent par ailleurs d\u2019une large diffusion pendant tout le XVIIIe si\u00e8cle.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"444\" data-attachment-id=\"16376\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/1267557-alb-65ad2c29a5da5\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bo\u00eetes de toilettes en vernis rouge et or.  (c) Galerie Pellat de Villedon, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Bo\u00eetes de toilettes en vernis rouge et or.&lt;br \/&gt;\n(c) Galerie Pellat de Villedon, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?fit=665%2C444&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?resize=665%2C444&#038;ssl=1\" alt=\"\" class=\"wp-image-16376\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c29a5da5.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Bo\u00eetes de toilettes en vernis rouge et or.  (c)<a href=\"https:\/\/www.proantic.com\/galerie\/pellatdevilledon\/\"> Galerie Pellat de Villedon<\/a>, Proantic<\/figcaption><\/figure>\n\n\n\n<p>Ces rares t\u00e9moins du d\u00e9but du si\u00e8cle ont peut-\u00eatre \u00e9t\u00e9 r\u00e9alis\u00e9 par Guillaume Martin et ses ateliers. En effet, l\u2019artisan donnant naissance \u00e0 une dynastie c\u00e9l\u00e8bre de vernisseur, innove et marque l\u2019histoire de la laque. Il devient \u00ab&nbsp;vernisseur du roy&nbsp;\u00bb \u00e0 partir de 1725. Les historiens s\u2019accordent \u00e0 dire que Guillaume et ses fr\u00e8res se sont impos\u00e9s dans ce domaine entre 1710 et 1730 face \u00e0 leurs concurrents. Dans les documents contemporains \u00e0 celui-ci nous retrouvons le titre \u00ab&nbsp;Guillaume Martin vernisseur au Verny de la Chine tant sur bois, benne, yvoir qu\u2019autres tant pour toilettes de femmes qu\u2019autres ouvrages&nbsp;\u00bb. Nous savons qu\u2019\u00e0 cette \u00e9poque les objets de toilettes et en particulier les bo\u00eetes carr\u00e9s \u00e9taient majeures dans son travail.&nbsp;<br>Elles \u00e9taient tr\u00e8s couteuses. Plus le d\u00e9cor \u00e9tait complexe, plus le prix \u00e9tait cons\u00e9quent comme nous l\u2019explique Anne Forray-Carlier dans le livre \u00ab&nbsp;Les secrets de la laque fran\u00e7aise&nbsp;\u00bb (\u00e9ditions Les arts d\u00e9coratifs). En choisissant telles bordures ou tels d\u00e9tails, le commanditaire avait un choix multiple de possibilit\u00e9s. Anecdote amusante, le duc de Bouillon devait 200 livres aux Martin (c\u2019est-\u00e0-dire une somme tr\u00e8s importante).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"444\" data-attachment-id=\"16377\" data-permalink=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/1267557-alb-65ad2c291feaa\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bo\u00eetes de toilettes en vernis rouge et or.  (c) Galerie Pellat de Villedon, Proantic\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Bo\u00eetes de toilettes en vernis rouge et or.&lt;br \/&gt;\n(c) Galerie Pellat de Villedon, Proantic&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?fit=665%2C444&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?resize=665%2C444&#038;ssl=1\" alt=\"\" class=\"wp-image-16377\" srcset=\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c291feaa.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/a><figcaption class=\"wp-element-caption\">Bo\u00eetes de toilettes en vernis rouge et or.  (c)<a href=\"https:\/\/www.proantic.com\/galerie\/pellatdevilledon\/*\"> Galerie Pellat de Villedon<\/a>, Proantic<\/figcaption><\/figure>\n\n\n\n<p>Nous remarquons que les oeuvres de notre \u00e9tude poss\u00e8dent un d\u00e9cor bien fait \u00e0 la main puisque les deux bo\u00eetes ont quelques diff\u00e9rences dans la gravure (par exemple pas le m\u00eame nombre de croisillons dans les angles). Elles pr\u00e9sentent dans les cartouches le mythe de Psych\u00e9 et d\u2019Eros (cupidon). V\u00e9nus, la m\u00e8re d\u2019Eros, repr\u00e9sent\u00e9 en petit putto ail\u00e9 muni de ses fl\u00e8ches, est jalouse de la beaut\u00e9 de Psych\u00e9 et indique \u00e0 l\u2019angelot d\u2019envoyer une fl\u00e8che \u00e0 Psych\u00e9 pour qu\u2019elle tombe amoureuse d&rsquo;un mortel qualifi\u00e9 du plus laid qui soit. Cupidon subjugu\u00e9 par la beaut\u00e9 de la jeune fille se pique sans faire expr\u00e8s et tombe amoureux d\u2019elle. Cette derni\u00e8re est repr\u00e9sent\u00e9e parfois en enfant comme ici et porte des ailes de papillons. Le sujet de l\u2019Amour auquel fait r\u00e9f\u00e9rence ces bo\u00eetes indique qu\u2019il s&rsquo;agit peut-\u00eatre d&rsquo;un cadeau de mariage.&nbsp;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros (cupidon) et V\u00e9nus. Autour des sc\u00e8nes principales, un riche d\u00e9cor de feuilles d\u2019acanthe, de corbeilles de fruits, d\u2019enroulements se d\u00e9ploient.Travail probable de Guillaume MartinEpoque Louis XIV (1710-1720) La paire [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":16378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[180],"tags":[],"class_list":["post-16373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arts-decoratifs-proantic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic<\/title>\n<meta name=\"description\" content=\"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic\" \/>\n<meta property=\"og:description\" content=\"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Magazine de Proantic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T13:52:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T14:08:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9line Autant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Autant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\"},\"author\":{\"name\":\"C\u00e9line Autant\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"headline\":\"Bo\u00eetes de toilettes en vernis rouge et or\",\"datePublished\":\"2024-01-30T13:52:19+00:00\",\"dateModified\":\"2024-03-12T14:08:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\"},\"wordCount\":1026,\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Arts d\u00e9coratifs sur Proantic\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\",\"url\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\",\"name\":\"Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic\",\"isPartOf\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2024-01-30T13:52:19+00:00\",\"dateModified\":\"2024-03-12T14:08:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\"},\"description\":\"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.proantic.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bo\u00eetes de toilettes en vernis rouge et or\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#website\",\"url\":\"https:\/\/www.proantic.com\/magazine\/\",\"name\":\"Le Magazine de Proantic\",\"description\":\"Magazine d&#039;art et expositions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315\",\"name\":\"C\u00e9line Autant\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic","description":"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/","og_locale":"fr_FR","og_type":"article","og_title":"Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic","og_description":"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros","og_url":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/","og_site_name":"Le Magazine de Proantic","article_publisher":"https:\/\/www.facebook.com\/pages\/Proantic\/\/259180871793","article_published_time":"2024-01-30T13:52:19+00:00","article_modified_time":"2024-03-12T14:08:26+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg","type":"image\/jpeg"}],"author":"C\u00e9line Autant","twitter_misc":{"\u00c9crit par":"C\u00e9line Autant","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#article","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/"},"author":{"name":"C\u00e9line Autant","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"headline":"Bo\u00eetes de toilettes en vernis rouge et or","datePublished":"2024-01-30T13:52:19+00:00","dateModified":"2024-03-12T14:08:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/"},"wordCount":1026,"image":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1","articleSection":["Arts d\u00e9coratifs sur Proantic"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/","url":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/","name":"Bo\u00eetes de toilettes en vernis rouge et or Le Magazine de Proantic","isPartOf":{"@id":"https:\/\/www.proantic.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage"},"image":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1","datePublished":"2024-01-30T13:52:19+00:00","dateModified":"2024-03-12T14:08:26+00:00","author":{"@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315"},"description":"Paire de bo\u00eetes de toilettes en vernis rouge et or dites \u00ab\u00a0carr\u00e9s\u00a0\u00bb fermant \u00e0 cl\u00e9. Le d\u00e9cor repr\u00e9sente au centre au sein de cartouches Pych\u00e9, Eros","breadcrumb":{"@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#primaryimage","url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.proantic.com\/magazine\/boites-de-toilettes-en-vernis-rouge-et-or\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.proantic.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Bo\u00eetes de toilettes en vernis rouge et or"}]},{"@type":"WebSite","@id":"https:\/\/www.proantic.com\/magazine\/#website","url":"https:\/\/www.proantic.com\/magazine\/","name":"Le Magazine de Proantic","description":"Magazine d&#039;art et expositions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proantic.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.proantic.com\/magazine\/#\/schema\/person\/1cd7872d300bf20ba8f564542dd5b315","name":"C\u00e9line Autant"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.proantic.com\/magazine\/wp-content\/uploads\/2024\/01\/1267557-alb-65ad2c298b76b.jpg?fit=1200%2C800&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7EkP3-4g5","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/16373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/comments?post=16373"}],"version-history":[{"count":2,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/16373\/revisions"}],"predecessor-version":[{"id":16380,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/posts\/16373\/revisions\/16380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media\/16378"}],"wp:attachment":[{"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/media?parent=16373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/categories?post=16373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proantic.com\/magazine\/wp-json\/wp\/v2\/tags?post=16373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}